{"id":11425,"count":46,"description":"","link":"https:\/\/positiveprints.com\/it\/categoria-prodotto\/regali-di-natale\/regali-di-natale-per-lei\/","name":"per Lei","slug":"regali-di-natale-per-lei","taxonomy":"product_cat","parent":5269,"meta":[],"menu_order":233,"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Regali di Natale per Lei - Positive Prints<\/title>\n<meta name=\"description\" content=\"Riscopri il calore delle festivit\u00e0 con i nostri regali di Natale per lei personalizzati. Un regalo sincero pu\u00f2 creare ricordi indimenticabili.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"per Lei Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/positiveprints.com\/it\/categoria-prodotto\/regali-di-natale\/regali-di-natale-per-lei\/\" \/>\n<meta property=\"og:site_name\" content=\"Positive Prints\" \/>\n<meta property=\"og:image\" content=\"https:\/\/positiveprints.com\/wp-content\/uploads\/2026\/03\/Open-graph-2026-1200x630-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Regali di Natale per Lei - Positive Prints","description":"Riscopri il calore delle festivit\u00e0 con i nostri regali di Natale per lei personalizzati. Un regalo sincero pu\u00f2 creare ricordi indimenticabili.","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"per Lei Archives","og_url":"https:\/\/positiveprints.com\/it\/categoria-prodotto\/regali-di-natale\/regali-di-natale-per-lei\/","og_site_name":"Positive Prints","og_image":[{"width":1200,"height":630,"url":"https:\/\/positiveprints.com\/wp-content\/uploads\/2026\/03\/Open-graph-2026-1200x630-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/positiveprints.com\/it\/categoria-prodotto\/regali-di-natale\/regali-di-natale-per-lei\/","url":"https:\/\/positiveprints.com\/it\/categoria-prodotto\/regali-di-natale\/regali-di-natale-per-lei\/","name":"Regali di Natale per Lei - Positive Prints","isPartOf":{"@id":"https:\/\/positiveprints.com\/it\/#website"},"description":"Riscopri il calore delle festivit\u00e0 con i nostri regali di Natale per lei personalizzati. Un regalo sincero pu\u00f2 creare ricordi indimenticabili.","breadcrumb":{"@id":"https:\/\/positiveprints.com\/it\/categoria-prodotto\/regali-di-natale\/regali-di-natale-per-lei\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/positiveprints.com\/it\/categoria-prodotto\/regali-di-natale\/regali-di-natale-per-lei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/positiveprints.com\/it\/"},{"@type":"ListItem","position":2,"name":"Natale","item":"https:\/\/positiveprints.com\/it\/categoria-prodotto\/regali-di-natale\/"},{"@type":"ListItem","position":3,"name":"per Lei"}]},{"@type":"WebSite","@id":"https:\/\/positiveprints.com\/it\/#website","url":"https:\/\/positiveprints.com\/it\/","name":"Positive Prints","description":"Amazing Custom Personalized Gifts","publisher":{"@id":"https:\/\/positiveprints.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/positiveprints.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/positiveprints.com\/it\/#organization","name":"Positive Prints","alternateName":"Positive Prints","url":"https:\/\/positiveprints.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/positiveprints.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/positiveprints.com\/wp-content\/uploads\/2026\/03\/245815646_1337939713319158_5671353136411139666_n.png","contentUrl":"https:\/\/positiveprints.com\/wp-content\/uploads\/2026\/03\/245815646_1337939713319158_5671353136411139666_n.png","width":800,"height":800,"caption":"Positive Prints"},"image":{"@id":"https:\/\/positiveprints.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/positiveprintscom","https:\/\/www.instagram.com\/positiveprintscom\/","https:\/\/www.tiktok.com\/@positiveprintscom","https:\/\/www.pinterest.com\/positiveprintscom\/"]}]}},"_links":{"self":[{"href":"https:\/\/positiveprints.com\/it\/wp-json\/wp\/v2\/product_cat\/11425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/positiveprints.com\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/positiveprints.com\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/positiveprints.com\/it\/wp-json\/wp\/v2\/product_cat\/5269"}],"wp:post_type":[{"href":"https:\/\/positiveprints.com\/it\/wp-json\/wp\/v2\/product?product_cat=11425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}