{"id":1666821,"date":"2026-03-09T09:49:59","date_gmt":"2026-03-09T08:49:59","guid":{"rendered":"https:\/\/positiveprints.com\/?post_type=product&#038;p=1666821"},"modified":"2026-08-29T15:06:27","modified_gmt":"2026-08-29T14:06:27","slug":"rallenta-art-collage","status":"publish","type":"product","link":"https:\/\/positiveprints.com\/it\/prodotto\/rallenta-art-collage\/","title":{"rendered":"Rallenta &#8211; Art Collage"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<ul class=\"check-list\">\n<li>Carica le tue foto preferite per personalizzare ogni lettera<\/li>\n<li>Includi un testo personalizzato amorevole<\/li>\n<li>Personalizza in 3 semplici passaggi<\/li>\n<li>Usa l\u2019anteprima interattiva per controllare subito il tuo progetto<\/li>\n<\/ul>\n","protected":false},"featured_media":1680123,"template":"","meta":[],"product_brand":[],"product_cat":[8830,7832,4449],"product_tag":[13811],"class_list":{"0":"post-1666821","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-collage-di-foto","7":"product_cat-regali-per-gli-amici","8":"product_cat-tutti-i-prodotti","9":"product_tag-poster-fotografico-personalizzato","11":"first","12":"instock","13":"sale","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/positiveprints.com\/it\/wp-json\/wp\/v2\/product\/1666821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/positiveprints.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/positiveprints.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/positiveprints.com\/it\/wp-json\/wp\/v2\/media\/1680123"}],"wp:attachment":[{"href":"https:\/\/positiveprints.com\/it\/wp-json\/wp\/v2\/media?parent=1666821"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/positiveprints.com\/it\/wp-json\/wp\/v2\/product_brand?post=1666821"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/positiveprints.com\/it\/wp-json\/wp\/v2\/product_cat?post=1666821"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/positiveprints.com\/it\/wp-json\/wp\/v2\/product_tag?post=1666821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}